{"id":635,"count":48,"description":"Uefa Europa League","link":"https:\/\/www.calciatori-online.com\/calcio\/notizie\/europa-league-uefa","name":"Europa League","slug":"europa-league-uefa","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Europa League: notizie, calendario partite, risultati, classifica, accoppiamenti, sorteggi, date<\/title>\n<meta name=\"description\" content=\"UEFA EUROPA LEAGUE: ultime news e notizie sui sorteggi, i gironi, le partite, gli accoppiamenti, i risultati.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.calciatori-online.com\/calcio\/notizie\/europa-league-uefa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/notizie\\\/europa-league-uefa\",\"url\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/notizie\\\/europa-league-uefa\",\"name\":\"Europa League: notizie, calendario partite, risultati, classifica, accoppiamenti, sorteggi, date\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/#website\"},\"description\":\"UEFA EUROPA LEAGUE: ultime news e notizie sui sorteggi, i gironi, le partite, gli accoppiamenti, i risultati.\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/#website\",\"url\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/\",\"name\":\"Calciatori-Online.com\",\"description\":\"Tutto Sui Giocatori di Calcio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/#organization\",\"name\":\"Calciatori-Online.com\",\"url\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/wp-content\\\/uploads\\\/calciatori-online-com.jpg\",\"contentUrl\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/wp-content\\\/uploads\\\/calciatori-online-com.jpg\",\"width\":370,\"height\":87,\"caption\":\"Calciatori-Online.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.calciatori-online.com\\\/calcio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europa League: notizie, calendario partite, risultati, classifica, accoppiamenti, sorteggi, date","description":"UEFA EUROPA LEAGUE: ultime news e notizie sui sorteggi, i gironi, le partite, gli accoppiamenti, i risultati.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.calciatori-online.com\/calcio\/notizie\/europa-league-uefa","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.calciatori-online.com\/calcio\/notizie\/europa-league-uefa","url":"https:\/\/www.calciatori-online.com\/calcio\/notizie\/europa-league-uefa","name":"Europa League: notizie, calendario partite, risultati, classifica, accoppiamenti, sorteggi, date","isPartOf":{"@id":"https:\/\/www.calciatori-online.com\/calcio\/#website"},"description":"UEFA EUROPA LEAGUE: ultime news e notizie sui sorteggi, i gironi, le partite, gli accoppiamenti, i risultati.","inLanguage":"it-IT"},{"@type":"WebSite","@id":"https:\/\/www.calciatori-online.com\/calcio\/#website","url":"https:\/\/www.calciatori-online.com\/calcio\/","name":"Calciatori-Online.com","description":"Tutto Sui Giocatori di Calcio","publisher":{"@id":"https:\/\/www.calciatori-online.com\/calcio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.calciatori-online.com\/calcio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.calciatori-online.com\/calcio\/#organization","name":"Calciatori-Online.com","url":"https:\/\/www.calciatori-online.com\/calcio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.calciatori-online.com\/calcio\/#\/schema\/logo\/image\/","url":"https:\/\/www.calciatori-online.com\/calcio\/wp-content\/uploads\/calciatori-online-com.jpg","contentUrl":"https:\/\/www.calciatori-online.com\/calcio\/wp-content\/uploads\/calciatori-online-com.jpg","width":370,"height":87,"caption":"Calciatori-Online.com"},"image":{"@id":"https:\/\/www.calciatori-online.com\/calcio\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.calciatori-online.com\/calcio\/wp-json\/wp\/v2\/categories\/635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.calciatori-online.com\/calcio\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.calciatori-online.com\/calcio\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.calciatori-online.com\/calcio\/wp-json\/wp\/v2\/posts?categories=635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}